{"id":3028,"date":"2024-11-09T18:33:35","date_gmt":"2024-11-09T16:33:35","guid":{"rendered":"https:\/\/dialexity.com\/blog\/?p=3028"},"modified":"2024-11-09T18:33:35","modified_gmt":"2024-11-09T16:33:35","slug":"argument-inspector-dialectical-insights","status":"publish","type":"post","link":"https:\/\/dialexity.com\/blog\/argument-inspector-dialectical-insights\/","title":{"rendered":"Argument Inspector: Dialectical Insights"},"content":{"rendered":"\n<p>A 90-second guide to dialectical features:<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 960 \/ 720;\" width=\"960\" controls src=\"https:\/\/dialexity.com\/blog\/wp-content\/uploads\/2024\/11\/Dialectical-Insights-Compressed.mp4\"><\/video><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dialexity.com\/start\">Join Beta-Testing<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dialexity.com\/blog\/aregument-inspector-conflict-resolution\/\">Argument Inspector in Conflict Resolution<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dialexity.com\/blog\/from-solo-to-sage\/\">From SOLO to SAGE<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dialexity.com\/blog\/argument-inspector-special-features\/\">Argument Inspector Special Features<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dialexity.com\/blog\/dialectical-ethics\/\">Dialectical Ethics<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A 90-second guide to dialectical features:<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3028","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/posts\/3028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/comments?post=3028"}],"version-history":[{"count":1,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/posts\/3028\/revisions"}],"predecessor-version":[{"id":3030,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/posts\/3028\/revisions\/3030"}],"wp:attachment":[{"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/media?parent=3028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/categories?post=3028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialexity.com\/blog\/wp-json\/wp\/v2\/tags?post=3028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}